{"id":4051,"date":"2023-03-01T09:27:54","date_gmt":"2023-03-01T08:27:54","guid":{"rendered":"https:\/\/www.fundacionmanantial.org\/la-infancia-y-sus-problemas-la-experiencia-infantil-en-escena\/"},"modified":"2023-03-01T09:27:54","modified_gmt":"2023-03-01T08:27:54","slug":"la-infancia-y-sus-problemas-la-experiencia-infantil-en-escena","status":"publish","type":"post","link":"https:\/\/www.fundacionmanantial.org\/en\/la-infancia-y-sus-problemas-la-experiencia-infantil-en-escena\/","title":{"rendered":"&#8220;La infancia y sus problemas, la experiencia infantil en escena&#8221;"},"content":{"rendered":"\n<p>He tenido la gran suerte de participar en la <strong>formaci\u00f3n de &#8220;La infancia y sus problemas, la experiencia infantil en escena&#8221;<\/strong> donde <a href=\"https:\/\/estebanlevin.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Esteban Levin<\/a> nos ha transmitido toda su experiencia y pasi\u00f3n por el <strong>trabajo con ni\u00f1os<\/strong>.<\/p>\n\n\n\n<p>Acercarse a los <strong>problemas infantiles<\/strong> tiene tanto de apasionante como de complicado. Nos cuestionamos c\u00f3mo entrar en el <strong>sufrimiento del ni\u00f1o<\/strong> cuando no existe una demanda, una posibilidad es recibir ese sufrimiento que nos habla de \u00e9l mismo y donarlo de otra manera diferente con el \u00fanico objetivo de <strong>ver qu\u00e9 ocurre<\/strong>. En relaci\u00f3n al juego con un ni\u00f1o cuesta soportar el sinsentido, porque al final l<strong>o que les angustia y nos angustia es todo aquello que no lo tiene<\/strong>. Quiz\u00e1 no sabemos qu\u00e9 hacemos ni para qu\u00e9, pero es un intento de <strong>que el ni\u00f1o encuentre otras maneras de hacer en el mundo a trav\u00e9s de las escenas que se van planteando.<\/strong><\/p>\n\n\n\n<p><strong>La tarea en la infancia es construir y es ah\u00ed donde nosotros podemos facilitar esa posibilidad, desde el armado de una experiencia conjunta que lleve a otro lugar donde puedan pasar otras cosas.<\/strong><\/p>\n\n\n\n<p>Me ha parecido una formaci\u00f3n apasionante, que ha supuesto una <strong>inyecci\u00f3n de motivaci\u00f3n<\/strong> para continuar con esta interesante tarea.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><em>Sara Molina. Casa Verde.<\/em><\/p>\n\n\n\n<div style=\"height:55px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>He tenido la gran suerte de participar en la formaci\u00f3n de &#8220;La infancia y sus problemas, la experiencia infantil en escena&#8221; donde Esteban Levin nos ha transmitido toda su experiencia y pasi\u00f3n por el trabajo con ni\u00f1os. Acercarse a los problemas infantiles tiene tanto de apasionante como de complicado. Nos cuestionamos c\u00f3mo entrar en el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3910,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[41],"tags":[485,713,84,242,98,714,413,86,65,111],"class_list":["post-4051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-salud-mental","tag-casaverde","tag-crecimiento","tag-formacion","tag-fundacionmanantial","tag-infancia","tag-nino","tag-proposito","tag-resiliencia","tag-salud-mental","tag-sensibilizacion"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fundacionmanantial.org\/en\/wp-json\/wp\/v2\/posts\/4051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fundacionmanantial.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fundacionmanantial.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fundacionmanantial.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fundacionmanantial.org\/en\/wp-json\/wp\/v2\/comments?post=4051"}],"version-history":[{"count":0,"href":"https:\/\/www.fundacionmanantial.org\/en\/wp-json\/wp\/v2\/posts\/4051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fundacionmanantial.org\/en\/wp-json\/wp\/v2\/media\/3910"}],"wp:attachment":[{"href":"https:\/\/www.fundacionmanantial.org\/en\/wp-json\/wp\/v2\/media?parent=4051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fundacionmanantial.org\/en\/wp-json\/wp\/v2\/categories?post=4051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fundacionmanantial.org\/en\/wp-json\/wp\/v2\/tags?post=4051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}